{"id":709,"date":"2019-09-09T17:53:24","date_gmt":"2019-09-09T21:53:24","guid":{"rendered":"http:\/\/www.cibt.net\/cn\/?p=709"},"modified":"2021-02-01T22:08:26","modified_gmt":"2021-02-01T22:08:26","slug":"%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97","status":"publish","type":"post","link":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/","title":{"rendered":"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757"},"content":{"rendered":"<p><strong>2019<\/strong><strong>\u5e74<\/strong><strong>8<\/strong><strong>\u6708<\/strong><strong>27<\/strong><strong>\u65e5-<\/strong><strong>\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2<\/strong>\uff08\u4ee5\u4e0b\u7b80\u79f0 \u201c\u67ab\u534e\u56fd\u9645\u201d\u6216\u201c\u516c\u53f8\u201d\uff09\uff08\u591a\u4f26\u591a\u8bc1\u5238\u4ea4\u6613\u6240\u4ee3\u7801\uff1aMBA\uff0cOTCQX\u56fd\u9645\u7248\u4ee3\u7801\uff1aMBAIF\uff09\u6b23\u6170\u5730\u5ba3\u5e03\uff0c\u5b50\u516c\u53f8GEC\u73af\u7403\u6559\u80b2\u57ce\u6709\u9650\u5408\u4f19\u5df2\u5b8c\u6210\u6536\u8d2d\u5c06\u7528\u4e8e\u53d1\u5c55\u7d20\u91cc\u5e02GEC\u73af\u7403\u6559\u80b2\u57ce\uff08\u201dEMC\u201d\uff09\u9879\u76ee\u7684\u571f\u5730\u3002\u571f\u5730\u8d2d\u4e70\u4ef7\u4e3a2260\u4e07\u52a0\u5143\uff0c\u5373\u6bcf\u53ef\u5efa\u5e73\u65b9\u82f1\u5c3a56\u52a0\u5143\uff0c\u53e6\u52a0\u94f6\u884c\u5229\u606f\u548c\u5f00\u53d1\u8d39\u3002\u8be5\u9879\u76ee\u6210\u672c\u8fdc\u4f4e\u4e8e\u90bb\u8fd1\u5730\u5757\u7684\u5176\u4ed6\u76f8\u4f3c\u7269\u4e1a\uff0c \u57282018\u5e7412\u6708\uff0c\u4e0e\u73af\u7403\u6559\u80b2\u57ce\u7d20\u91cc\u9879\u76ee\u76f8\u90bb\u7269\u4e1a\u4ee5\u6bcf\u53ef\u5efa\u5e73\u65b9\u82f1\u5c3a106\u52a0\u5143\u7684\u4ef7\u683c\u552e\u51fa\u3002<\/p>\n<p>EMC\u539f\u6765\u7684\u8bbe\u8ba1\u662f55\u5c42\uff0c55\u4e07\u5e73\u65b9\u82f1\u5c3a\u9ad8\u5c42\u6df7\u51dd\u571f\u591a\u7528\u9014\u5efa\u7b51\uff0c\u5305\u542b\u5b66\u6821\uff0c\u529e\u516c\u5ba4\uff0c\u9152\u5e97\u4ee5\u53ca\u79df\u8d41\u516c\u5bd3\u3002\u7ecf\u8fc7\u5ba1\u614e\u8003\u91cf\u540e,\u548c\u6709\u5f85\u7d20\u91cc\u5e02\u6279\u51c6,EMC\u91cd\u65b0\u8bbe\u8ba1\u4e3a39\u5c42\uff0c\u603b\u5efa\u7b51\u9762\u4e3a40.4\u4e07\u5e73\u65b9\u82f1\u5c3a\u3002\u4fee\u6539\u540e\u7684\u9879\u76ee\u5c06\u88ab\u8bbe\u8ba1\u6210\u591a\u7528\u9014\u5efa\u7b51\uff0c\u5305\u62ec\u5206\u6743\u7684\u5fae\u578b\u516c\u5bd3\uff0c\u79df\u8d41\u516c\u5bd3\uff0c\u4e3a\u6559\u80b2\u5b66\u6821\u8bbe\u8ba1\u7684\u5546\u7528\u529e\u516c\u533a\u57df\u4ee5\u53ca\u56db\u5c42\u914d\u5957\u4fbf\u5229\u8bbe\u65bd\u3002\u76f8\u8f83\u539f\u8bbe\u8ba1\u9884\u7b97\uff0c\u516c\u53f8\u6b64\u6b21\u7684\u65b0\u8bbe\u8ba1\u548c\u589e\u503c\u5de5\u7a0b\u9884\u8ba1\u5c06\u7ed9\u6574\u4e2a\u9879\u76ee\u8282\u7701\u8fd15000\u4e07\u52a0\u5143\u7684\u9884\u7b97\uff0c \u518d\u52a0\u4e0a\u6700\u8fd1\u5efa\u8bbe\u548c\u878d\u8d44\u6210\u672c\u4e0b\u964d\uff0c\u6210\u672c\u964d\u4f4e\u7684\u6548\u679c\u5c06\u66f4\u663e\u8457\u3002<\/p>\n<p>\u201c\u80fd\u591f\u66f4\u6709\u6548\u5730\u5229\u7528\u7a7a\u95f4\uff0c\u5c06EMC\u7684\u5efa\u9020\u6210\u672c\u964d\u4f4e\uff0c\u6211\u4eec\u611f\u5230\u975e\u5e38\u6b23\u559c\u201d\u67ab\u534e\u56fd\u9645\u8463\u4e8b\u957f\u3001\u603b\u88c1\u517c\u9996\u5e2d\u6267\u884c\u5b98\u6731\u4efb\u91cd\u5148\u751f\u8bc4\u8bba\u9053\uff0c\u201c\u7d20\u91cc\u5e02\u653f\u5e9c\u6700\u8fd1\u5ba3\u5e03\u91cd\u65b0\u5f00\u53d1\u7d20\u91cc\u5e02\u4e2d\u5fc3\uff0c\u5c06\u6709200\u591a\u4e07\u5e73\u65b9\u82f1\u5c3a\u7684\u533a\u57df\u88ab\u91cd\u65b0\u8bbe\u8ba1\u548c\u5347\u7ea7\u3002\u8981\u91cd\u5f00\u53d1\u7684\u4e2d\u5fc3\u533a\u57df\u79bb\u6211\u4eecEMC\u9879\u76ee\u8ddd\u79bb\u4e0d\u523050\u82f1\u5c3a\u3002\u6709\u4e86\u8fd9\u4e9b\u65b0\u6279\u51c6\u7684\u5f00\u53d1\u548c\u5347\u7ea7\uff0c\u6211\u4eec\u66f4\u770b\u597dEMC\u9879\u76ee\u7684\u524d\u666f\u3002\u201d<\/p>\n<p>\u8bf7\u6d4f\u89c8\u4ee5\u4e0b\u94fe\u63a5\uff0c\u67e5\u9605\u6709\u5173\u7d20\u91cc\u4e2d\u5fc3\u6539\u9020\u7684\u65b0\u95fb\u62a5\u9053\uff1a<\/p>\n<p><a href=\"https:\/\/urbansurrey.com\/category\/development\/\">https:\/\/urbansurrey.com\/category\/development\/<\/a><\/p>\n<p><a href=\"https:\/\/dailyhive.com\/vancouver\/surrey-central-bus-exchange-recreation-centre-redevelopment\">https:\/\/dailyhive.com\/vancouver\/surrey-central-bus-exchange-recreation-centre-redevelopment<\/a><u>and<\/u><\/p>\n<p><strong>\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u9879\u76ee\u7b80\u4ecb\uff1a<\/strong><\/p>\n<p>\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u9879\u76ee\u00ae\u7ecf\u8fc7\u91cd\u65b0\u8bbe\u8ba1\u540e\uff0c\u5c06\u5bb9\u7eb3800\u591a\u4f4d\u79df\u6237\uff0c\u4e3a5\u523010\u6240\u5b66\u6821\u63d0\u4f9b\u5546\u4e1a\u529e\u516c\u533a\u57df\uff0c\u63d0\u4f9b\u5b8c\u5584\u7684\u4fbf\u5229\u8bbe\u65bd\u3002\u9664\u7ed9\u73af\u7403\u6559\u80b2\u57ce\u5185\u7684\u6559\u80b2\u793e\u533a\u63d0\u4f9b\u670d\u52a1\u5916\uff0cEMC\u8fd8\u5c06\u4e3a\u5c31\u8bfb\u9644\u8fd1\u5b66\u6821\u7684\u5b66\u751f\u63d0\u4f9b\u670d\u52a1\u3002\u6bd4\u5982\u897f\u8499\u83f2\u6c99\u5927\u5b66\u7d20\u91cc\u6821\u533a\u548c\u6606\u7279\u5170\u7406\u5de5\u5927\u5b66\uff0c \u8fd9\u4e24\u6240\u5b66\u6821\u4f4d\u4e8e\u73af\u7403\u6559\u80b2\u57ce\u7684\u5bf9\u9762\uff0c\u975e\u5e38\u65b9\u4fbf\u3002\u9053\u683c\u62c9\u65af\u5b66\u9662\u7d20\u91cc\u57f9\u8bad\u4e2d\u5fc3\u4ee5\u53ca\u535a\u5b66\u5b66\u9662\u7d20\u91cc\u6821\u533a\u4e5f\u90fd\u5728\u73af\u7403\u6559\u80b2\u57ce1.5\u516c\u91cc\u4e4b\u5185\u3002<\/p>\n<p><strong>\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2\u7b80\u4ecb\uff1a<\/strong><\/p>\n<p>\u52a0\u62ff\u5927\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2\uff08CIBT\uff09\u662f\u52a0\u62ff\u5927\u6700\u5927\u7684\u6559\u80b2\u548c\u6559\u80b2\u623f\u5730\u4ea7\u6295\u8d44\u516c\u53f8\u4e4b\u4e00\uff0c\u81ea1994\u5e74\u4ee5\u6765\uff0c\u67ab\u534e\u56fd\u9645\u4e13\u6ce8\u4e8e\u52a0\u62ff\u5927\u548c\u56fd\u9645\u6559\u80b2\u5e02\u573a\uff0c\u5e76\u5728\u591a\u4f26\u591a\u8bc1\u5238\u4ea4\u6613\u6240\u53ca\u7f8e\u56fdOTCQX\u5e02\u573a\u56fd\u9645\u7248\u4e0a\u5e02\u3002\u67ab\u534e\u56fd\u9645\u5728\u52a0\u62ff\u5927\u548c\u6d77\u5916\u62e5\u6709\u5546\u5b66\u9662\u548c\u8bed\u8a00\u5b66\u9662\u3001\u5b66\u751f\u516c\u5bd3\u7269\u4e1a\u3001\u62db\u751f\u4e2d\u5fc3\u548c\u529e\u516c\u573a\u6240\u7b49\u5171\u8ba145\u4e2a\u8fd0\u8425\u573a\u6240\u3002\u96c6\u56e2\u6bcf\u5e74\u5165\u5b66\u4eba\u6570\u8d85\u8fc712,000\u3002\u96c6\u56e2\u7684\u6559\u80b2\u5e73\u53f0\u5305\u62ec\u521b\u529e\u4e8e1903\u5e74\u7684\u52a0\u62ff\u5927\u535a\u5b66\u5b66\u9662\u3001\u52a0\u62ff\u5927\u535a\u5b66\u8bed\u8a00\u5b66\u9662\u3001\u6e29\u54e5\u534e\u56fd\u9645\u5b66\u9662\u548c\u4e2d\u52a0\u5546\u5b66\u9662\u3002\u901a\u8fc7\u8fd9\u4e9b\u5b66\u6821\uff0c\u67ab\u534e\u56fd\u9645\u63d0\u4f9b\u533b\u7597\u62a4\u7406\u3001\u9152\u5e97\u7ba1\u7406\u3001\u8bed\u8a00\u57f9\u8bad\u7b49\u9886\u57df\u7684\u5de5\u5546\u548c\u7ba1\u7406\u8bfe\u7a0b\u4ee5\u53ca\u8d85\u8fc7150\u9879\u804c\u4e1a\u3001\u8bed\u8a00\u4e0e\u4e13\u4e1a\u57f9\u8bad\u8bfe\u7a0b\u3002\u56fd\u9645\u6559\u80b2\u57ce\u63a7\u80a1\u6709\u9650\u516c\u53f8\uff08\u201c\u56fd\u9645\u6559\u80b2\u57ce\u201d\uff09\u662f\u67ab\u534e\u56fd\u9645\u65d7\u4e0b\u7684\u623f\u5730\u4ea7\u5f00\u53d1\uff0c\u63a7\u80a1\u4e0e\u7ba1\u7406\u516c\u53f8\uff0c\u4e13\u6ce8\u6559\u80b2\u623f\u5730\u4ea7\u9879\u76ee\uff0c\u4f8b\u5982\u5b66\u751f\u9152\u5e97\u3001\u670d\u52a1\u516c\u5bd3\u4ee5\u53ca\u56fd\u9645\u6559\u80b2\u57ce\u9879\u76ee\uff0c\u65d7\u4e0b\u6295\u8d44\u7ec4\u5408\u548c\u5f00\u53d1\u4e2d\u7684\u9879\u76ee\u9884\u7b97\u8d85\u8fc710\u4ebf\u52a0\u5143\u3002\u56fd\u9645\u6559\u80b2\u57ce\u63a7\u80a1\u516c\u53f8\u65d7\u4e0b\u7684\u7269\u4e1a\u6bcf\u5e74\u4e3a\u8d85\u8fc71500\u540d\u7684\u5b66\u751f\u53ca\u79df\u5ba2\u63d0\u4f9b\u4f4f\u5bbf\u670d\u52a1\u3002\u96c6\u56e2\u65d7\u4e0b\u516c\u53f8\u8fd8\u5305\u62ec\uff1a\u56fd\u9645\u6559\u80b2\u8054\u76df\uff08\u201cGEA\u201d\uff09\u548c\u827a\u529b\u521b\u4f5c\u516c\u53f8\uff08\u201c\u827a\u529b\u521b\u4f5c\u201d\uff09\u3002\u56fd\u9645\u6559\u80b2\u8054\u76df\u4e3a\u4f17\u591a\u7684\u5317\u7f8e\u7cbe\u82f1\u5e7c\u513f\u56ed\u3001\u5c0f\u5b66\u3001\u4e2d\u5b66\u548c\u5927\u5b66\u62db\u6536\u56fd\u9645\u7559\u5b66\u751f\u3002\u827a\u529b\u521b\u4f5c\u662f\u4e00\u5bb6\u603b\u90e8\u8bbe\u5728\u52a0\u62ff\u5927\u6e29\u54e5\u534e\u4ece\u4e8b\u8bbe\u8ba1\u4e0e\u5e7f\u544a\u7684\u884c\u4e1a\u5148\u950b\u3002\u6b22\u8fce\u6d4f\u89c8www.cibt.net\u5e76\u89c2\u770b\u6211\u4eec\u7684\u4f01\u4e1a\u5ba3\u4f20\u7247\u3002<\/p>\n<p>\u66f4\u591a\u4fe1\u606f\u8bf7\u8054\u7cfb\uff1a<\/p>\n<p>\u6731\u4efb\u91cd<\/p>\n<p>\u8463\u4e8b\u957f\u3001\u603b\u88c1\u517c\u9996\u5e2d\u6267\u884c\u5b98<\/p>\n<p>\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2<\/p>\n<p><strong>\u6295\u8d44\u8005\u8054\u7cfb\u7535\u8bdd\uff1a<\/strong><strong>1-604-871-9909<\/strong><strong>\uff0c\u5206\u673a\u53f7<\/strong><strong>318<\/strong><strong>\uff0c\u6216\u8005\u53d1\u90ae\u4ef6\u81f3\uff1a<\/strong><a href=\"mailto:info@cibt.net\"><strong>info@cibt.net<\/strong><\/a><\/p>\n<p><strong>\u524d\u77bb\u6027\u9648\u8ff0\uff1a<\/strong><\/p>\n<p>\u672c\u65b0\u95fb\u7a3f\u4e2d\u7684\u4e00\u4e9b\u58f0\u660e\u5305\u542b\u6709\u5173\u52a0\u62ff\u5927\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2\u53ca\u5176\u8ba1\u5212\u7684\u524d\u77bb\u6027\u4fe1\u606f\uff08\u201c\u524d\u77bb\u6027\u58f0\u660e\u201d\uff09\u3002\u524d\u77bb\u6027\u9648\u8ff0\u662f\u975e\u5386\u53f2\u4e8b\u5b9e\u7684\u9648\u8ff0\uff0c\u5728\u6b64\u4efd\u65b0\u95fb\u7a3f\u4e2d\u5305\u62ec\u4f46\u4e0d\u9650\u4e8e\u5bf9\u4e8e\u67ab\u534e\u56fd\u9645\u65d7\u4e0b\u5206\u516c\u53f8\u6240\u6295\u8d44\u7684\u73af\u7403\u6559\u80b2\u57ce\u9879\u76ee\u89c4\u5212\u8bbe\u8ba1\u7684\u63cf\u8ff0\u3002\u524d\u77bb\u6027\u9648\u8ff0\u53d7\u5404\u79cd\u98ce\u9669\uff0c\u4e0d\u786e\u5b9a\u6027\u548c\u5176\u4ed6\u56e0\u7d20\u7684\u5f71\u54cd\uff08\u7edf\u79f0\u201c\u98ce\u9669\u201d\uff09\uff0c\u8fd9\u4e9b\u56e0\u7d20\u53ef\u80fd\u5bfc\u81f4CIBT\u7684\u5b9e\u9645\u4e1a\u7ee9\u6216\u6210\u679c\u4e0e\u524d\u77bb\u6027\u9648\u8ff0\u4e2d\u8868\u8fbe\u6216\u6697\u793a\u7684\u5185\u5bb9\u5927\u4e0d\u76f8\u540c\u3002\u8fd9\u4e9b\u98ce\u9669\u5305\u62ec\u4f46\u4e0d\u9650\u4e8e\u73af\u7403\u6559\u80b2\u57ce\u6709\u9650\u5408\u4f19\u516c\u53f8\u7684\u878d\u8d44\u80fd\u529b\uff0c\u5e38\u89c4\u7684\u5efa\u8bbe\u98ce\u9669\uff0c\u4ee5\u53ca\u80fd\u5426\u83b7\u5f97\u5e02\u653f\u6240\u8981\u6c42\u7684\u5168\u90e8\u8bb8\u53ef\u3002\u524d\u77bb\u6027\u9648\u8ff0\u57fa\u4e8e\u67ab\u534e\u56fd\u9645\u7ba1\u7406\u5c42\u5728\u4f5c\u51fa\u9648\u8ff0\u65f6\u7684\u4fe1\u5ff5\u3001\u610f\u89c1\u548c\u671f\u671b\uff0c\u5982\u679c\u8fd9\u4e9b\u4fe1\u5ff5\u3001\u610f\u89c1\u6216\u671f\u671b\u6216\u5176\u4ed6\u60c5\u51b5\u53d1\u751f\u53d8\u5316\uff0c\u67ab\u534e\u56fd\u9645\u4e0d\u627f\u62c5\u66f4\u65b0\u5176\u524d\u77bb\u6027\u9648\u8ff0\u7684\u4e49\u52a1\uff0c\u9664\u975e\u6cd5\u5f8b\u5bf9\u6b64\u53e6\u6709\u89c4\u5b9a\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2019\u5e748\u670827\u65e5-\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2\uff08\u4ee5\u4e0b &#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-709","post","type-post","status-publish","format-standard","hentry","category-cibt-corporate-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757 - GEC Corp. - CN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gechq.com\/cn\/2019\/09\/09\/\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757 - GEC Corp. - CN\" \/>\n<meta property=\"og:description\" content=\"2019\u5e748\u670827\u65e5-\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2\uff08\u4ee5\u4e0b ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gechq.com\/cn\/2019\/09\/09\/\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757\/\" \/>\n<meta property=\"og:site_name\" content=\"GEC Corp. - CN\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-09T21:53:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T22:08:26+00:00\" \/>\n<meta name=\"author\" content=\"cibteditor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"cibteditor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/\"},\"author\":{\"name\":\"cibteditor\",\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/#\\\/schema\\\/person\\\/324b29f88f571e205e75bf0b373d9912\"},\"headline\":\"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757\",\"datePublished\":\"2019-09-09T21:53:24+00:00\",\"dateModified\":\"2021-02-01T22:08:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/\"},\"wordCount\":37,\"articleSection\":[\"\u73af\u7403\u6559\u80b2\u57ce\u96c6\u56e2\u65b0\u95fb\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/\",\"url\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/\",\"name\":\"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757 - GEC Corp. - CN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/#website\"},\"datePublished\":\"2019-09-09T21:53:24+00:00\",\"dateModified\":\"2021-02-01T22:08:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/#\\\/schema\\\/person\\\/324b29f88f571e205e75bf0b373d9912\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/2019\\\/09\\\/09\\\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gechq.com\\\/cn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/#website\",\"url\":\"https:\\\/\\\/gechq.com\\\/cn\\\/\",\"name\":\"GEC Corp. - CN\",\"description\":\"Just another GECHQ site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gechq.com\\\/cn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gechq.com\\\/cn\\\/#\\\/schema\\\/person\\\/324b29f88f571e205e75bf0b373d9912\",\"name\":\"cibteditor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d790cc124d8ff87cbd1fa9814c06a46d3059e0288cf6fb628cfcb637106ce6a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d790cc124d8ff87cbd1fa9814c06a46d3059e0288cf6fb628cfcb637106ce6a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d790cc124d8ff87cbd1fa9814c06a46d3059e0288cf6fb628cfcb637106ce6a2?s=96&d=mm&r=g\",\"caption\":\"cibteditor\"},\"url\":\"https:\\\/\\\/gechq.com\\\/cn\\\/author\\\/cibteditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757 - GEC Corp. - CN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gechq.com\/cn\/2019\/09\/09\/\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757\/","og_locale":"zh_CN","og_type":"article","og_title":"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757 - GEC Corp. - CN","og_description":"2019\u5e748\u670827\u65e5-\u67ab\u534e\u56fd\u9645\u6559\u80b2\u6295\u8d44\u96c6\u56e2\uff08\u4ee5\u4e0b ...","og_url":"https:\/\/gechq.com\/cn\/2019\/09\/09\/\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757\/","og_site_name":"GEC Corp. - CN","article_published_time":"2019-09-09T21:53:24+00:00","article_modified_time":"2021-02-01T22:08:26+00:00","author":"cibteditor","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"cibteditor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/#article","isPartOf":{"@id":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/"},"author":{"name":"cibteditor","@id":"https:\/\/gechq.com\/cn\/#\/schema\/person\/324b29f88f571e205e75bf0b373d9912"},"headline":"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757","datePublished":"2019-09-09T21:53:24+00:00","dateModified":"2021-02-01T22:08:26+00:00","mainEntityOfPage":{"@id":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/"},"wordCount":37,"articleSection":["\u73af\u7403\u6559\u80b2\u57ce\u96c6\u56e2\u65b0\u95fb"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/","url":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/","name":"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757 - GEC Corp. - CN","isPartOf":{"@id":"https:\/\/gechq.com\/cn\/#website"},"datePublished":"2019-09-09T21:53:24+00:00","dateModified":"2021-02-01T22:08:26+00:00","author":{"@id":"https:\/\/gechq.com\/cn\/#\/schema\/person\/324b29f88f571e205e75bf0b373d9912"},"breadcrumb":{"@id":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gechq.com\/cn\/2019\/09\/09\/%e6%9e%ab%e5%8d%8e%e5%9b%bd%e9%99%85%e5%ad%90%e5%85%ac%e5%8f%b8%e5%ae%8c%e6%88%90%e6%94%b6%e8%b4%ad%e7%b4%a0%e9%87%8c%e5%b8%82%e7%8e%af%e7%90%83%e6%95%99%e8%82%b2%e5%9f%8e%e5%9c%b0%e5%9d%97\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gechq.com\/cn\/"},{"@type":"ListItem","position":2,"name":"\u67ab\u534e\u56fd\u9645\u5b50\u516c\u53f8\u5b8c\u6210\u6536\u8d2d\u7d20\u91cc\u5e02\u73af\u7403\u6559\u80b2\u57ce\u5730\u5757"}]},{"@type":"WebSite","@id":"https:\/\/gechq.com\/cn\/#website","url":"https:\/\/gechq.com\/cn\/","name":"GEC Corp. - CN","description":"Just another GECHQ site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gechq.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/gechq.com\/cn\/#\/schema\/person\/324b29f88f571e205e75bf0b373d9912","name":"cibteditor","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/d790cc124d8ff87cbd1fa9814c06a46d3059e0288cf6fb628cfcb637106ce6a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d790cc124d8ff87cbd1fa9814c06a46d3059e0288cf6fb628cfcb637106ce6a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d790cc124d8ff87cbd1fa9814c06a46d3059e0288cf6fb628cfcb637106ce6a2?s=96&d=mm&r=g","caption":"cibteditor"},"url":"https:\/\/gechq.com\/cn\/author\/cibteditor\/"}]}},"_links":{"self":[{"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/posts\/709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/comments?post=709"}],"version-history":[{"count":1,"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/posts\/709\/revisions"}],"predecessor-version":[{"id":1165,"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/posts\/709\/revisions\/1165"}],"wp:attachment":[{"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/media?parent=709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/categories?post=709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gechq.com\/cn\/wp-json\/wp\/v2\/tags?post=709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}